{"id":150857,"date":"2015-03-10T09:00:38","date_gmt":"2015-03-10T08:00:38","guid":{"rendered":"http:\/\/www.monblogdefille.com\/blog\/?p=150857"},"modified":"2015-03-13T17:11:41","modified_gmt":"2015-03-13T16:11:41","slug":"le-rose-aux-joues","status":"publish","type":"post","link":"https:\/\/www.monblogdefille.com\/blog\/le-rose-aux-joues\/","title":{"rendered":"Le rose aux joues"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-150858\" src=\"http:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2015\/03\/blush_rose-2.jpg\" alt=\"blush_rose 2\" width=\"700\" height=\"584\" srcset=\"https:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2015\/03\/blush_rose-2.jpg 700w, https:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2015\/03\/blush_rose-2-300x250.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Vous connaissez (ou pas ;-) ma passion d\u00e9mentielle pour les blushes dans tous les tons de corail, je porte rarement autre chose sur mes joues.<\/p>\n<p>Ces derniers temps certains de mes fonds de teint \u00e9taient trop chauds pour ma carnation de fin d&rsquo;hiver, du coup pour contrebalancer \u00e7a j&rsquo;ai port\u00e9 plus souvent du vrai rose sur les joues, comme celui de <a href=\"http:\/\/tinyurl.com\/gnhoajq\" target=\"_blank\" rel=\"noopener\"><strong>Clarins<\/strong> <\/a>(08 Sweet Rose) ou ce <a href=\"http:\/\/tidd.ly\/7a5011a6\" target=\"_blank\" rel=\"noopener\"><strong>Kiss &amp; Blush Yves Saint Laurent<\/strong><\/a> (8 Pink H\u00e9doniste).<\/p>\n<p>Ca marche super bien pour donner un vrai coup de fra\u00eecheur au teint un peu plomb\u00e9 par trop de jaune (d&rsquo;ailleurs si on ajoutait du bronzer ou un blush plus orang\u00e9 \u00e7a pourrait \u00eatre encore pire). Le rose n&rsquo;est donc pas r\u00e9serv\u00e9 aux looks sur peaux tr\u00e8s p\u00e2les genre \u00ab\u00a0je viens de marcher dans la for\u00eat enneig\u00e9e\u00a0\u00bb mais fonctionne aussi tr\u00e8s bien sur une peau plus dor\u00e9e.<\/p>\n<p>Il faut dire que ce sont deux roses tr\u00e8s doux et vraiment faciles, qui ne demandent m\u00eame pas d&rsquo;efforts dingues pour trouver le rouge \u00e0 l\u00e8vres qui ne va pas clasher avec.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-150858\" src=\"http:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2015\/03\/blush_rose-2.jpg\" alt=\"blush_rose 2\" width=\"700\" height=\"584\" srcset=\"https:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2015\/03\/blush_rose-2.jpg 700w, https:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2015\/03\/blush_rose-2-300x250.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"author":3,"featured_media":150858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1485],"tags":[20094],"class_list":["post-150857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-maquillage","tag-blush"],"_links":{"self":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/posts\/150857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/comments?post=150857"}],"version-history":[{"count":0,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/posts\/150857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/media\/150858"}],"wp:attachment":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/media?parent=150857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/categories?post=150857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/tags?post=150857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}