{"id":127356,"date":"2009-04-20T07:58:51","date_gmt":"2009-04-20T05:58:51","guid":{"rendered":"http:\/\/www.monblogdefille.com\/blog\/?p=127356"},"modified":"2016-08-15T20:13:23","modified_gmt":"2016-08-15T18:13:23","slug":"la-halle-aux-chaussures-la-fashion-pas-chere","status":"publish","type":"post","link":"https:\/\/www.monblogdefille.com\/blog\/la-halle-aux-chaussures-la-fashion-pas-chere\/","title":{"rendered":"La Halle aux Chaussures, la fashion pas ch\u00e8re"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-127357\" title=\"tong-python\" src=\"http:\/\/www.monblogdefille.com\/blog\/wp-content\/uploads\/2009\/04\/tong-python.jpg\" alt=\"tong-python\" width=\"300\" height=\"199\" align=\"left\" \/>J&rsquo;ai \u00e9crit quelques petits trucs sur le site de la Halle aux Chaussures, allez donc faire un tour et voir <a href=\"http:\/\/www.mesenvies-meschaussures.com\/index?utm_source=blog&amp;utm_medium=blogdefille&amp;utm_campaign=nvellecope2009%2B \" target=\"_blank\" rel=\"noopener\">mes coups de c\u0153ur<\/a> : vous serez surprise de d\u00e9couvrir que c&rsquo;est vraiment joli et mode (pour quasi peanuts, ce qui n&rsquo;est jamais n\u00e9gligeable).<\/p>\n<p>Il y a vraiment plusieurs petites paires de chaussures qui me tentent bien, c&rsquo;est tendance sans \u00eatre d\u00e9lirant et immettable, j&rsquo;aime bien.<\/p>\n<p>Et puis il y a un jeu-concours en ce moment\u00a0: vous pouvez gagner 500 \u20ac de shopping et de paires de chaussures, \u00e7a se refuse pas\u00a0;-)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai \u00e9crit quelques petits trucs sur le site de la Halle aux Chaussures, allez donc faire un tour et voir mes coups de c\u0153ur : vous serez surprise de d\u00e9couvrir que c&rsquo;est vraiment joli et&#8230;<br \/> <a class=\"read-more\" href=\"https:\/\/www.monblogdefille.com\/blog\/la-halle-aux-chaussures-la-fashion-pas-chere\/\">Lire la suite \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":127357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20177],"tags":[20082],"class_list":["post-127356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode","tag-concours"],"_links":{"self":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/posts\/127356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/comments?post=127356"}],"version-history":[{"count":0,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/posts\/127356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/media\/127357"}],"wp:attachment":[{"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/media?parent=127356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/categories?post=127356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monblogdefille.com\/blog\/wp-json\/wp\/v2\/tags?post=127356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}